{"id":7569,"date":"2025-01-30T10:15:04","date_gmt":"2025-01-30T09:15:04","guid":{"rendered":"https:\/\/biolotta.de\/gewuerzuniversum\/?post_type=recipe&#038;p=7569"},"modified":"2025-01-30T10:15:05","modified_gmt":"2025-01-30T09:15:05","slug":"tuerkische-pasta","status":"publish","type":"recipe","link":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/","title":{"rendered":"T\u00fcrkische Pasta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":7570,"comment_status":"open","ping_status":"closed","template":"","meta":[],"recipe-course":[],"recipe-cuisine":[],"recipe-cooking-method":[],"recipe-tag":[289,304,310],"recipe-key":[],"recipe-badge":[],"recipe-dietary":[],"class_list":["post-7569","recipe","type-recipe","status-publish","has-post-thumbnail","hentry","recipe-tag-leichte-kueche","recipe-tag-pasta","recipe-tag-tuerkisch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00fcrkische Pasta - BioLotta.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00fcrkische Pasta - BioLotta.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/\" \/>\n<meta property=\"og:site_name\" content=\"BioLotta.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BioLotta-Gew%c3%bcrze-113151033788160\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-30T09:15:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2025\/01\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"489\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/\",\"name\":\"T\u00fcrkische Pasta - BioLotta.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg\",\"datePublished\":\"2025-01-30T09:15:04+00:00\",\"dateModified\":\"2025-01-30T09:15:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg\",\"contentUrl\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg\",\"width\":489,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/tuerkische-pasta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rezepte\",\"item\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/recipe\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00fcrkische Pasta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#website\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/\",\"name\":\"BioLotta.de\",\"description\":\"BioLotta | Nachhaltig w\u00fcrzen - Gutes tun!\",\"publisher\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#organization\",\"name\":\"Biolotta\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/biolotta_logo.svg\",\"contentUrl\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/biolotta_logo.svg\",\"width\":\"164\",\"height\":\"111\",\"caption\":\"Biolotta\"},\"image\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BioLotta-Gew\u00fcrze-113151033788160\",\"https:\\\/\\\/www.instagram.com\\\/biolotta_gewuerze\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/BioLotta_Gewuerze\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00fcrkische Pasta - BioLotta.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/","og_locale":"de_DE","og_type":"article","og_title":"T\u00fcrkische Pasta - BioLotta.de","og_url":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/","og_site_name":"BioLotta.de","article_publisher":"https:\/\/www.facebook.com\/BioLotta-Gew%c3%bcrze-113151033788160","article_modified_time":"2025-01-30T09:15:05+00:00","og_image":[{"width":489,"height":750,"url":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2025\/01\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/","url":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/","name":"T\u00fcrkische Pasta - BioLotta.de","isPartOf":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/#primaryimage"},"image":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/#primaryimage"},"thumbnailUrl":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2025\/01\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg","datePublished":"2025-01-30T09:15:04+00:00","dateModified":"2025-01-30T09:15:05+00:00","breadcrumb":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/#primaryimage","url":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2025\/01\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg","contentUrl":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2025\/01\/25_01_Tuerkische_Pasta_Stylingkitchen_Coverfoto_-1.jpg","width":489,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/tuerkische-pasta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/biolotta.de\/gewuerzuniversum\/"},{"@type":"ListItem","position":2,"name":"Rezepte","item":"https:\/\/biolotta.de\/gewuerzuniversum\/recipe\/"},{"@type":"ListItem","position":3,"name":"T\u00fcrkische Pasta"}]},{"@type":"WebSite","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#website","url":"https:\/\/biolotta.de\/gewuerzuniversum\/","name":"BioLotta.de","description":"BioLotta | Nachhaltig w\u00fcrzen - Gutes tun!","publisher":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biolotta.de\/gewuerzuniversum\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#organization","name":"Biolotta","url":"https:\/\/biolotta.de\/gewuerzuniversum\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#\/schema\/logo\/image\/","url":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2020\/07\/biolotta_logo.svg","contentUrl":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2020\/07\/biolotta_logo.svg","width":"164","height":"111","caption":"Biolotta"},"image":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BioLotta-Gew\u00fcrze-113151033788160","https:\/\/www.instagram.com\/biolotta_gewuerze\/","https:\/\/www.pinterest.de\/BioLotta_Gewuerze\/"]}]}},"_links":{"self":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe\/7569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe"}],"about":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/types\/recipe"}],"author":[{"embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/comments?post=7569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/media\/7570"}],"wp:attachment":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/media?parent=7569"}],"wp:term":[{"taxonomy":"recipe-course","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-course?post=7569"},{"taxonomy":"recipe-cuisine","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-cuisine?post=7569"},{"taxonomy":"recipe-cooking-method","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-cooking-method?post=7569"},{"taxonomy":"recipe-tag","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-tag?post=7569"},{"taxonomy":"recipe-key","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-key?post=7569"},{"taxonomy":"recipe-badge","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-badge?post=7569"},{"taxonomy":"recipe-dietary","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-dietary?post=7569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}