{"id":6794,"date":"2023-06-22T14:32:11","date_gmt":"2023-06-22T12:32:11","guid":{"rendered":"https:\/\/biolotta.de\/gewuerzuniversum\/?post_type=recipe&#038;p=6794"},"modified":"2023-06-26T13:55:02","modified_gmt":"2023-06-26T11:55:02","slug":"ofengemuese-mit-gegrillten-hackbaellchen","status":"publish","type":"recipe","link":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/","title":{"rendered":"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":5612,"comment_status":"open","ping_status":"closed","template":"","meta":[],"recipe-course":[],"recipe-cuisine":[],"recipe-cooking-method":[],"recipe-tag":[],"recipe-key":[],"recipe-badge":[],"recipe-dietary":[],"class_list":["post-6794","recipe","type-recipe","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen - BioLotta.de<\/title>\n<meta name=\"description\" content=\"Peppe dein Gem\u00fcse auf - mit unseren Rezept und dem Rosa Salz aus der Gew\u00fcrzm\u00fchle von BioLotta! Damit schmeckt das Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen super aromatisch!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen - BioLotta.de\" \/>\n<meta property=\"og:description\" content=\"Peppe dein Gem\u00fcse auf - mit unseren Rezept und dem Rosa Salz aus der Gew\u00fcrzm\u00fchle von BioLotta! Damit schmeckt das Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen super aromatisch!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/\" \/>\n<meta property=\"og:site_name\" content=\"BioLotta.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BioLotta-Gew%c3%bcrze-113151033788160\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:55:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2022\/06\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1022\" \/>\n\t<meta property=\"og:image:height\" content=\"1022\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/\",\"name\":\"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen - BioLotta.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg\",\"datePublished\":\"2023-06-22T12:32:11+00:00\",\"dateModified\":\"2023-06-26T11:55:02+00:00\",\"description\":\"Peppe dein Gem\u00fcse auf - mit unseren Rezept und dem Rosa Salz aus der Gew\u00fcrzm\u00fchle von BioLotta! Damit schmeckt das Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen super aromatisch!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg\",\"contentUrl\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg\",\"width\":1022,\"height\":1022,\"caption\":\"Rezeptbild Ofengem\u00fcse mit Hackb\u00e4llchen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/Rezepte\\\/ofengemuese-mit-gegrillten-hackbaellchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rezepte\",\"item\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/recipe\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#website\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/\",\"name\":\"BioLotta.de\",\"description\":\"BioLotta | Nachhaltig w\u00fcrzen - Gutes tun!\",\"publisher\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#organization\",\"name\":\"Biolotta\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/biolotta_logo.svg\",\"contentUrl\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/biolotta_logo.svg\",\"width\":\"164\",\"height\":\"111\",\"caption\":\"Biolotta\"},\"image\":{\"@id\":\"https:\\\/\\\/biolotta.de\\\/gewuerzuniversum\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BioLotta-Gew\u00fcrze-113151033788160\",\"https:\\\/\\\/www.instagram.com\\\/biolotta_gewuerze\\\/\",\"https:\\\/\\\/www.pinterest.de\\\/BioLotta_Gewuerze\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen - BioLotta.de","description":"Peppe dein Gem\u00fcse auf - mit unseren Rezept und dem Rosa Salz aus der Gew\u00fcrzm\u00fchle von BioLotta! Damit schmeckt das Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen super aromatisch!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/","og_locale":"de_DE","og_type":"article","og_title":"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen - BioLotta.de","og_description":"Peppe dein Gem\u00fcse auf - mit unseren Rezept und dem Rosa Salz aus der Gew\u00fcrzm\u00fchle von BioLotta! Damit schmeckt das Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen super aromatisch!","og_url":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/","og_site_name":"BioLotta.de","article_publisher":"https:\/\/www.facebook.com\/BioLotta-Gew%c3%bcrze-113151033788160","article_modified_time":"2023-06-26T11:55:02+00:00","og_image":[{"width":1022,"height":1022,"url":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2022\/06\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/","url":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/","name":"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen - BioLotta.de","isPartOf":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/#primaryimage"},"image":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/#primaryimage"},"thumbnailUrl":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2022\/06\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg","datePublished":"2023-06-22T12:32:11+00:00","dateModified":"2023-06-26T11:55:02+00:00","description":"Peppe dein Gem\u00fcse auf - mit unseren Rezept und dem Rosa Salz aus der Gew\u00fcrzm\u00fchle von BioLotta! Damit schmeckt das Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen super aromatisch!","breadcrumb":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/#primaryimage","url":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2022\/06\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg","contentUrl":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2022\/06\/22-06_Ofengemuese_mit_Hackbaellchen_Stylingkitchen_Cover_5-e1656400581142.jpg","width":1022,"height":1022,"caption":"Rezeptbild Ofengem\u00fcse mit Hackb\u00e4llchen"},{"@type":"BreadcrumbList","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/Rezepte\/ofengemuese-mit-gegrillten-hackbaellchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/biolotta.de\/gewuerzuniversum\/"},{"@type":"ListItem","position":2,"name":"Rezepte","item":"https:\/\/biolotta.de\/gewuerzuniversum\/recipe\/"},{"@type":"ListItem","position":3,"name":"Ofengem\u00fcse mit gegrillten Hackb\u00e4llchen"}]},{"@type":"WebSite","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#website","url":"https:\/\/biolotta.de\/gewuerzuniversum\/","name":"BioLotta.de","description":"BioLotta | Nachhaltig w\u00fcrzen - Gutes tun!","publisher":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biolotta.de\/gewuerzuniversum\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#organization","name":"Biolotta","url":"https:\/\/biolotta.de\/gewuerzuniversum\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#\/schema\/logo\/image\/","url":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2020\/07\/biolotta_logo.svg","contentUrl":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-content\/uploads\/2020\/07\/biolotta_logo.svg","width":"164","height":"111","caption":"Biolotta"},"image":{"@id":"https:\/\/biolotta.de\/gewuerzuniversum\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BioLotta-Gew\u00fcrze-113151033788160","https:\/\/www.instagram.com\/biolotta_gewuerze\/","https:\/\/www.pinterest.de\/BioLotta_Gewuerze\/"]}]}},"_links":{"self":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe\/6794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe"}],"about":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/types\/recipe"}],"author":[{"embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/comments?post=6794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/media\/5612"}],"wp:attachment":[{"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/media?parent=6794"}],"wp:term":[{"taxonomy":"recipe-course","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-course?post=6794"},{"taxonomy":"recipe-cuisine","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-cuisine?post=6794"},{"taxonomy":"recipe-cooking-method","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-cooking-method?post=6794"},{"taxonomy":"recipe-tag","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-tag?post=6794"},{"taxonomy":"recipe-key","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-key?post=6794"},{"taxonomy":"recipe-badge","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-badge?post=6794"},{"taxonomy":"recipe-dietary","embeddable":true,"href":"https:\/\/biolotta.de\/gewuerzuniversum\/wp-json\/wp\/v2\/recipe-dietary?post=6794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}